{"id":862,"date":"2020-06-17T11:27:58","date_gmt":"2020-06-17T09:27:58","guid":{"rendered":"http:\/\/typologieanalytique.com\/?page_id=862"},"modified":"2022-12-12T11:09:50","modified_gmt":"2022-12-12T10:09:50","slug":"la-typologie-jungienne","status":"publish","type":"page","link":"https:\/\/typologieanalytique.com\/index.php\/la-typologie-jungienne\/","title":{"rendered":"La typologie jungienne"},"content":{"rendered":"\n<h2 class=\"has-text-align-center has-light-green-cyan-color has-text-color has-large-font-size wp-block-heading\" id=\"lexique-haut\">La typologie jungienne<\/h2>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-normal-font-size\">La th\u00e9orie des types issue de <em>Types psychologiques<\/em> de C. G. Jung constitue ce qu&rsquo;on appelle la typologie jungienne. C&rsquo;est la base th\u00e9orique de tous les mod\u00e8les typologiques \u00e0 seize types.<br><br>En typologie jungienne, chaque type est nomm\u00e9 par sa fonction dominante, sans acronyme (ex : Penseur introverti). Le c\u00e2blage cognitif n&rsquo;est constitu\u00e9 que de quatre <a href=\"https:\/\/typologieanalytique.com\/index.php\/lexique\/\">fonctions \u00e9gosyntoniques<\/a> (comme en typologie myersienne) mais seules les attitudes de la fonction dominante et de la fonction inf\u00e9rieure sont distingu\u00e9es &#8211; l&rsquo;attitude des fonctions auxiliaire et tertiaire restant incertaine.<br><br>La th\u00e9orie des types de Jung constitue la base de la typologie analytique, et bien qu&rsquo;elle ait \u00e9t\u00e9 raffin\u00e9e et pr\u00e9cis\u00e9e par ses continuateurs, et \u00e9tendue par les apports de la typologie des profondeurs, la typologie analytique est encore en parfait alignement th\u00e9orique et m\u00e9thodologique avec la typologie jungienne.<\/p>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"les-contributeurs\">Les contributeurs<\/h5>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:16px\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Carl_Gustav_Jung\">Carl Gustav Jung<\/a> [Psychiatre, fondateur de la Psychologie Analytique]<\/p>\n\n\n\n<p class=\"has-text-align-center\" style=\"font-size:16px\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Marie-Louise_von_Franz\">Marie-Louise Von Franz<\/a> [Analyste, \u00e9l\u00e8ve de C. G. Jung]<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-sommaire\">Sommaire<\/h5>\n\n\n\n<p class=\"has-text-align-center has-normal-font-size\"><a href=\"#jung-freud-adler\">Jung, Freud et Adler<\/a><br><a href=\"#CGJ-les-types-psychologiques\">Les types psychologiques<\/a><br><a href=\"#CGJ-les-deux-attitudes\">Les deux attitudes : l&rsquo;introversion et l&rsquo;extraversion<\/a><br><a href=\"#CGJ-les-quatre-fonctions\">Les quatre fonctions<\/a><br><a href=\"#CGJ-les-quatre-types-principaux\">Les quatre types principaux<\/a><br><a href=\"#CGJ-les-huit-type-attitude\">Les huit type-attitude<\/a><br><a href=\"#CGJ-la-fonction-inf\u00e9rieure\">La fonction inf\u00e9rieure<\/a><br><a href=\"#CGJ-la-fonction-auxiliaire\">La fonction auxiliaire<\/a><br><a href=\"#CGJ-les-sous-types\" data-type=\"internal\" data-id=\"#CGJ-les-sous-types\">Les quatre sous-types<\/a><br><a href=\"#CGJ-le-mod\u00e8le-a-seize-types\">Le mod\u00e8le \u00e0 seize types<\/a><br><a href=\"#CGJ-la-fonction-tertiaire\">La fonction tertiaire<\/a><br><a href=\"#CGJ-en-r\u00e9sum\u00e9\">En r\u00e9sum\u00e9<\/a><br><a href=\"#CGJ-oppos\u00e9s-et-\u00e9quilibre-psychique\">Oppos\u00e9s et \u00e9quilibre psychique<\/a><br><a href=\"#CGJ-inconscient-selon-Jung\">L\u2019inconscient selon Jung<\/a><br><a href=\"#CGJ-pour-aller-plus-loin\">Pour aller plus loin<\/a><\/p>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"jung-freud-adler\">Jung, Freud et Adler<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">La th\u00e9orie des types de Jung est n\u00e9e \u00e0 l\u2019origine du besoin que Jung avait de comprendre pourquoi ses perspectives sur la psychologie \u00e9taient radicalement diff\u00e9rentes de celles de Sigmund Freud et d\u2019Alfred Adler. Afin de comprendre la source de ce qui les opposent, Jung d\u00e9cide de mettre en suspens ses recherches sur l\u2019inconscient et s\u2019int\u00e9resse au type psychologique qui d\u00e9termine d\u00e8s le d\u00e9part le jugement d\u2019une personne. D\u00e9couvrir que des attitudes conscientes diff\u00e9rentes expliquent les diff\u00e9rences entre les th\u00e9ories psychologiques de Freud et d\u2019Adler m\u00e8ne Jung \u00e0 voir que ces diff\u00e9rents types de conscience expliquent en grande partie les probl\u00e9matiques et les diff\u00e9rences qu\u2019il observe chez ses patients.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-les-types-psychologiques\">Les types psychologiques<\/h5>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image aligncenter size-medium is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"197\" height=\"300\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/317f0o5K4bL._SX326_BO1204203200_-197x300.jpg\" alt=\"\" class=\"wp-image-950\" srcset=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/317f0o5K4bL._SX326_BO1204203200_-197x300.jpg 197w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/317f0o5K4bL._SX326_BO1204203200_.jpg 328w\" sizes=\"(max-width: 197px) 100vw, 197px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">Jung publie Les types psychologiques en 1921. C\u2019est dans cet ouvrage de r\u00e9f\u00e9rence qu\u2019il expose l\u2019existence des deux attitudes de la psych\u00e9 humaine : l\u2019introversion et l\u2019extraversion. Il y explique que ces deux \u00e9nergies oppos\u00e9es sont compl\u00e9mentaires et que quand l\u2019une des attitudes est consciente, la seconde attitude est inconsciente et \u00e9quilibre la premi\u00e8re par un ph\u00e9nom\u00e8ne de compensation. Il ajoute que tout le monde poss\u00e8de bien les deux m\u00e9canismes, l\u2019extraversion et l\u2019introversion, et que seule la relative pr\u00e9dominance de l\u2019une ou de l\u2019autre d\u00e9termine le type de la personne. <\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-les-deux-attitudes\">Les deux attitudes : l&rsquo;introversion et l&rsquo;extraversion<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Par \u00ab attitude \u00bb Jung entend l\u2019attitude d\u2019une personne par rapport \u00e0 un objet ext\u00e9rieur \u00e0 elle \u2014 que ce soit une autre personne ou bien son environnement. <\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">\u00ab\u00a0L\u2019attitude de l\u2019introverti par rapport \u00e0 l\u2019objet est une attitude d\u2019abstraction; au fond, l\u2019introverti est toujours r\u00e9solu \u00e0 pr\u00e9server son \u00e9nergie de l\u2019objet, comme s\u2019il essayait d\u2019emp\u00eacher l\u2019objet de gagner du pouvoir sur lui. L\u2019extraverti, au contraire, a une relation positive \u00e0 l\u2019objet. L\u2019importance de l\u2019objet pour lui est telle qu\u2019il est constamment en relation avec l\u2019objet, affect\u00e9 et orient\u00e9 par lui. [&#8230;] Chacun peut constater le contraste absolument saisissant entre [les introvertis] ces personnes r\u00e9serv\u00e9es, insondables, parfois timides et [les extravertis] ces personnes ouvertes, sociables, enjou\u00e9es qui semblent toujours \u00eatre en bons termes avec tout le monde, ou toujours se disputer avec tout le monde, mais qui au final sont toujours en relation avec les autres d\u2019une mani\u00e8re ou d\u2019une autre.\u00a0\u00bb<br><em>Psychological Types<\/em><\/p>\n\n\n\n<p class=\"has-normal-font-size\">Pour Jung l\u2019introversion est une \u00e9nergie dirig\u00e9e vers l\u2019int\u00e9rieur de l\u2019individu, et l\u2019extraversion une \u00e9nergie dirig\u00e9e vers l\u2019ext\u00e9rieur de l\u2019individu. Les objets diminuent la puissance de l\u2019introverti, alors qu\u2019ils augmentent celle de l\u2019extraverti. L\u2019introverti se d\u00e9charge au contact des autres et de l\u2019environnement ext\u00e9rieur, alors que l\u2019extraverti, lui, se recharge \u00e0 leur contact.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-les-quatre-fonctions\">Les quatre fonctions<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">A ces deux attitudes introvertie (I) et extravertie (E) s\u2019ajoutent quatre fonctions cognitives, c\u2019est \u00e0 dire des fa\u00e7ons pour le cerveau humain de recueillir de l\u2019information et de la traiter. <br><br>Les quatre fonctions d\u00e9finies par Jung sont :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>La sensation <\/strong><br>S<br><em>Sensation<\/em><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>L\u2019 intuition <\/strong><br>N<br><em>iNtuition<\/em><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>La pens\u00e9e <\/strong><br>T<br><em>Thinking<\/em><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le sentiment <\/strong><br>F<br><em>Feeling<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-normal-font-size\">Ces quatre fonctions sont subdivis\u00e9es en deux groupes en fonction qu\u2019elles servent \u00e0 recueillir de l\u2019information ou qu\u2019elles servent \u00e0 les traiter :<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-8 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>Fonctions irrationnelles<br>Fonctions d&rsquo;observation<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>La sensation<\/strong><br>(S &#8211; Sensation)<\/td><td><strong>L\u2019intuition<\/strong><br>(N &#8211; iNtuition)<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">Les deux fonctions qui recueillent de l\u2019information sont cat\u00e9goris\u00e9es par Jung en tant que fonctions irrationnelles \u2014 dans le sens philosophique du terme, c\u2019est-\u00e0-dire d\u00e9passant l\u2019entendement humain. Ces fonction sont \u00e9galement appel\u00e9es fonctions d\u2019observation car elle servent \u00e0 observer le monde int\u00e9rieur et ext\u00e9rieur. Ce sont les fonctions de sensation et d\u2019intuition.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-12 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction rationnelles<br>Fonction de d\u00e9cision<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><strong>La pens\u00e9e <\/strong><br><\/strong>(T &#8211; Thinking)<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le sentiment <\/strong><br>(F &#8211; Feeling)<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">Les fonctions de pens\u00e9e et de sentiment sont, elles, cat\u00e9goris\u00e9es en tant que fonctions rationnelles, c\u2019est \u00e0 dire qu\u2019elles \u00e9voluent dans un cadre que le cerveau humain peut comprendre et nommer. Elles sont \u00e9galement appel\u00e9es fonctions de jugement, et elles servent \u00e0 traiter les informations observ\u00e9es en y appliquant un filtre de jugement. Ce sont ces fonctions qui motivent et permettent l\u2019action et la prise de d\u00e9cision.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-les-quatre-types-principaux\">Les quatre types principaux<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Si une fonction pr\u00e9domine chez une personne, alors le type de la personne correspond \u00e0 cette fonction principale. <br><br>Jung distingue ainsi quatre types de personnes :<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-16 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le type sensation<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le type intuition<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le type pens\u00e9e<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Le type sentiment <\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color wp-block-heading\" id=\"CGJ-les-huit-type-attitude\">Les huit type-attitude<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Chacun des quatre types sus-cit\u00e9s peut \u00eatre soit introverti soit extraverti en fonction de la relation que la personne a \u00e0 l\u2019objet. Ainsi il existe huit type-attitude : quatre extravertis et quatre introvertis. <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-20 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Les quatre types extravertis<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>sensation extravertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>intuition extravertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>pens\u00e9e extravertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>sentiment extraverti<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-stackable-spacer stk-block-spacer stk--no-padding stk-block stk-a0222ae\" data-block-id=\"a0222ae\"><style>.stk-a0222ae{height:30px !important}<\/style><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-24 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Les quatre types introvertis<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>sensation introvertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>intuition introvertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>pens\u00e9e introvertie<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type<\/strong><br><strong>sentiment introverti<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color wp-block-heading\" id=\"CGJ-la-fonction-inf\u00e9rieure\">La fonction inf\u00e9rieure<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Lorsque Jung parlent de fonction inf\u00e9rieure il le fait bien souvent au pluriel, car il consid\u00e8re que toute fonction en dehors de la fonction principale est une fonction moins diff\u00e9renci\u00e9e et donc inf\u00e9rieure \u00e0 la principale.<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">\u00ab\u00a0Elles [les fonctions inf\u00e9rieures] \u00e9taient \u00e0 l&rsquo;origine n\u00e9glig\u00e9es et r\u00e9prim\u00e9es parce qu&rsquo;elles emp\u00eachaient l&rsquo;homme civilis\u00e9 d&rsquo;atteindre ses objectifs. [&#8230;] Tant que l&rsquo;objectif culturel ne co\u00efncide pas avec l&rsquo;id\u00e9al de perfectionner l&rsquo;individualit\u00e9 humaine, ces fonctions sont sujettes \u00e0 d\u00e9pr\u00e9ciation et \u00e0 un certain degr\u00e9 de r\u00e9pression.\u00a0\u00bb<br> <em>Psychological Types<\/em> <\/p>\n\n\n\n<p class=\"has-normal-font-size\">Cependant il distingue parmi toutes ces fonctions indiff\u00e9renci\u00e9es la fonction qui \u00e9quilibre la fonction principale : <em>la<\/em> fonction inf\u00e9rieure. <br><br>Par souci de compensation, la nature et l&rsquo;attitude de la fonction inf\u00e9rieure sont toujours oppos\u00e9es \u00e0 celles de la fonction principale.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment introverti<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment extraverti<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment extraverti<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment introverti<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e introvertie<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-28 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-26 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">(Le m\u00eame tableau, mais avec le codage des fonctions) :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Si<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Si.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color wp-block-heading\" id=\"CGJ-la-fonction-auxiliaire\">La fonction auxiliaire<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">A la toute fin de sa description g\u00e9n\u00e9rale des types, Jung parle de l\u2019existence d\u2019une autre fonction, moins diff\u00e9renci\u00e9e que la principale et de moindre importance, qui est cependant invariablement pr\u00e9sente dans la conscience de la personne et qui exerce une influence conjointe avec la fonction principale : c\u2019est la fonction auxiliaire ou compl\u00e9mentaire.<br><br>Il est \u00e0 noter que lorsque Jung dit qu\u2019une fonction est consciente, conscientis\u00e9e ou diff\u00e9renci\u00e9e, cela signifie que cette fonction peut \u00eatre mobilis\u00e9e et utilis\u00e9e de fa\u00e7on volontaire. La fonction auxiliaire se d\u00e9marque donc lorsqu\u2019elle est diff\u00e9renci\u00e9e par une ob\u00e9issance \u00e0 la volont\u00e9 de la personne. Elle n\u2019est utile \u00e0 la personne et ne peut exister en tant qu\u2019auxiliaire que dans le cas pr\u00e9cis o\u00f9 elle ne cherche pas \u00e0 prendre l\u2019ascendant sur la fonction principale et o\u00f9 elle la sert sans chercher \u00e0 acqu\u00e9rir une quelconque autonomie. <br><br>Quant \u00e0 la nature de cette fonction auxiliaire, Jung pr\u00e9cise qu\u2019elle ne peut pas \u00eatre oppos\u00e9e \u00e0 celle de la fonction dominante. Ainsi une fonction sentiment ne pourra jamais \u00eatre la fonction auxiliaire d\u2019une fonction principale de pens\u00e9e, parce que la nature m\u00eame de ces deux fonctions est radicalement oppos\u00e9e. Une fonction principale de pens\u00e9e ne pourra jamais qu\u2019avoir une fonction de sensation ou d\u2019intuition en auxiliaire.<br><br>Nous nous retrouvons donc avec ce mod\u00e8le :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>introverti ou extraverti<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction auxiliaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>ou<br>sentiment<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>ou<br>sentiment<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>ou<br>intuition<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>ou<br>intuition<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition  <br>extravertie ou introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>extravertie ou introvertie <\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>extravertie ou introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>extravertie ou introvertie<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-30 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">(Le m\u00eame tableau, mais avec le codage des fonctions) :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Si<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction auxiliaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Si<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-32 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-les-sous-types\">Les quatre sous-types<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Ainsi peut-on identifier quatre sous-types venant compl\u00e9ter les huit type-attitude principaux, ce qui au total donne seize types psychologiques diff\u00e9rents :<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-34 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 1<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type sensation introvertie<\/td><td>Sous-type pens\u00e9e<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 2<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type sentiment<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type sensation extravertie <\/td><td>Sous-type pens\u00e9e<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 4<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type sentiment<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 5<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type intuition introvertie<\/td><td>Sous-type pens\u00e9e<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 6<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type sentiment<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 7<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type intuition extravertie<\/td><td>Sous-type pens\u00e9e<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 8<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type sentiment<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 9<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type pens\u00e9e introvertie<\/td><td>Sous-type sensation<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 10<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type intuition<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 11<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type pens\u00e9e extravertie<\/td><td>Sous-type sensation<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 12<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type intuition<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 13<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type sentiment introverti<\/td><td>Sous-type sensation<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 14<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type intuition<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 15<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Type sentiment extraverti<\/td><td>Sous-type sensation<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 16<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td>Sous-type intuition<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">(Le m\u00eame tableau, mais avec le codage des fonctions) :<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-36 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 1<\/strong><\/td><td>Type Si \/ sous-type T<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 2<\/strong><\/td><td>Type Si \/ sous-type F<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 3<\/strong><\/td><td>Type Se \/ sous-type T<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 4<\/strong><\/td><td>Type Se \/ sous-type F<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 5<\/strong><\/td><td>Type Ni \/ sous-type T<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 6<\/strong><\/td><td>Type Ni \/ sous-type F<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 7<\/strong><\/td><td>Type Ne \/ sous-type T<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 8<\/strong><\/td><td>Type Ne \/ sous-type F<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 9<\/strong><\/td><td>Type Ti \/ sous-type S<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 10<\/strong><\/td><td>Type Ti \/ sous-type N<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 11<\/strong><\/td><td>Type Te \/ sous-type S<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 12<\/strong><\/td><td>Type Te \/ sous-type N<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 13<\/strong><\/td><td>Type Fi \/ sous-type S<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 14<\/strong><\/td><td>Type Fi \/ sous-type N<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Types 15<\/strong><\/td><td>Type Fe \/ sous-type S<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Type 16<\/strong><\/td><td>Type Fe \/ sous-type N<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-le-mod\u00e8le-a-seize-types\">Le mod\u00e8le \u00e0 seize types<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Un passage de <em>Gifts Differing<\/em> (p.21) d&rsquo;Isabelle Myers pourrait induire en erreur quant \u00e0 l\u2019appartenance intellectuelle du mod\u00e8le \u00e0 seize type :<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">\u00ab\u00a0Quand le processus auxiliaire est pris en consid\u00e9ration, cela scinde chacun des types de Jung en deux. Plut\u00f4t que de n\u2019avoir qu\u2019un penseur introverti, nous obtenons un type pens\u00e9e introvertie sensation et un type pens\u00e9e introvertie intuition. <strong>Ainsi il y a seize types en lieu des huit de Jung<\/strong>.\u00a0\u00bb<br> <em>Gifts Differing<\/em> <\/p>\n\n\n\n<p class=\"has-normal-font-size\">Cependant, comme nous venons de le voir, la fonction auxiliaire et le mod\u00e8le \u00e0 seize type qui en d\u00e9coule ont bien \u00e9t\u00e9 th\u00e9oris\u00e9s par Jung. Il est vrai que Jung a pr\u00e9sent\u00e9 ces types psychologiques via leur fonction-attitude principale, au nombre de huit, mais c\u2019\u00e9tait dans un souci de clart\u00e9. Ces huit \u00ab types pures \u00bb constituaient des mod\u00e8les purement th\u00e9oriques destin\u00e9s \u00e0 donner des rep\u00e8res clairs aux analystes pouvant les aider \u00e0 rep\u00e9rer la fonction principale de leurs patients afin de pouvoir mieux identifier leurs n\u00e9vroses et communiquer plus efficacement avec eux.<br><br>Affirmer que Jung n\u2019avait cr\u00e9\u00e9 que huit types psychologiques est au mieux une erreur, au pire une appropriation abusive de la propri\u00e9t\u00e9 intellectuelle d\u2019autrui. Dans les deux cas, il nous semblait n\u00e9cessaire de clarifier ce point aupr\u00e8s des lecteurs.<br><br>Dans son chapitre sur la fonction auxiliaire Jung \u00e9nonce clairement le r\u00e9sultat typologique de la combinaison d\u2019une fonction principale et d\u2019une fonction auxiliaire, ainsi que la place de la fonction tertiaire :<\/p>\n\n\n\n<p class=\"has-very-light-gray-background-color has-background\">\u00ab\u00a0Les combinaisons r\u00e9sultantes [d&rsquo;une fonction principale associ\u00e9e \u00e0 une fonction auxiliaire] pr\u00e9sentent l&rsquo;image famili\u00e8re, par exemple, de la pens\u00e9e pratique alli\u00e9e \u00e0 la sensation, de la pens\u00e9e sp\u00e9culative progressant avec l&rsquo;intuition, de l&rsquo;intuition artistique s\u00e9lectionnant et pr\u00e9sentant sa vision \u00e0 l&rsquo;aide de valeurs et de ressenti, de l\u2019intuition philosophique syst\u00e9matisant sa vision en pens\u00e9e globale au moyen d&rsquo;un intellect puissant, etc. Les fonctions inconscientes se regroupent \u00e9galement dans des sch\u00e9mas corr\u00e9l\u00e9s aux fonctions conscientes. Ainsi, le corr\u00e9latif d\u2019une pens\u00e9e pratique consciente peut \u00eatre une attitude de sentiment et d\u2019intuition inconsciente, avec un sentiment soumis \u00e0 une plus forte inhibition que l&rsquo;intuition.\u00a0\u00bb<br><em>Psychological Types<\/em><\/p>\n\n\n\n<p class=\"has-normal-font-size\">Le mod\u00e8le \u00e0 seize types est n\u00e9, et il sera repris par tous les continuateurs de Jung apr\u00e8s lui.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-la-fonction-tertiaire\">La fonction tertiaire<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">M\u00eame si dans <em>Types psychologiques<\/em>, apr\u00e8s avoir pr\u00e9sent\u00e9 la fonction principale, la fonction auxiliaire et la fonction inf\u00e9rieure, Jung n&rsquo;a pas explicitement nomm\u00e9 la fonction indiff\u00e9renci\u00e9e restante, ses continuateurs on choisi de l&rsquo;appeler la fonction tertiaire. <br><br>Les deux fonctions se disputant la place de la fonction auxiliaire sont deux fonctions de m\u00eame nature : <\/p>\n\n\n\n<ul><li> Fonctions d\u2019observation (N ou S) si la fonction principale est une fonction de jugement (T ou F)<br><\/li><li> Fonctions de jugement (T ou F) si la fonction principale est une fonction d\u2019observation (N ou S)<\/li><\/ul>\n\n\n\n<p class=\"has-normal-font-size\">Pour que l\u2019une des deux fonctions soit auxiliaire, l\u2019autre doit prendre la place de la fonction tertiaire. C\u2019est \u00e0 la fonction la plus inhib\u00e9e des deux qu&rsquo;\u00e9choit la troisi\u00e8me place.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>introvertie ou extravertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>introverti ou extraverti<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction auxiliaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>ou<br>sentiment<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>ou<br>sentiment<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>ou<br>intuition<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>ou<br>intuition<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction tertiaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>ou<br>pens\u00e9e<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>ou<br>pens\u00e9e<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition<br>ou<br>sensation<\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition<br>ou<br>sensation<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">intuition<br>extravertie ou introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sensation<br>extravertie ou introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">sentiment<br>extravertie ou introvertie<\/td><td class=\"has-text-align-center\" data-align=\"center\">pens\u00e9e<br>extravertie ou introvertie<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-38 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"has-normal-font-size\">(Le m\u00eame tableau, mais avec le codage des fonctions) :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction principale<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Si<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction auxiliaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">T ou F<\/td><td class=\"has-text-align-center\" data-align=\"center\">S ou N<\/td><td class=\"has-text-align-center\" data-align=\"center\">S ou N<\/td><td class=\"has-text-align-center\" data-align=\"center\">S ou N<\/td><td class=\"has-text-align-center\" data-align=\"center\">S ou N<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction tertiaire<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><td class=\"has-text-align-center\" data-align=\"center\">F ou T<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Fonction inf\u00e9rieure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Ne<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ni<\/td><td class=\"has-text-align-center\" data-align=\"center\">Se<\/td><td class=\"has-text-align-center\" data-align=\"center\">Si<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fi<\/td><td class=\"has-text-align-center\" data-align=\"center\">Te<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ti<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-en-r\u00e9sum\u00e9\">En r\u00e9sum\u00e9<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">En r\u00e9sum\u00e9 en typologie jungienne la fonction principale, la fonction la plus diff\u00e9renci\u00e9e, a une attitude claire &#8211; soit extravertie soit introvertie, d\u00e9termin\u00e9e par l\u2019attitude pr\u00e9f\u00e9r\u00e9e de la personne. Si la personne est introvertie et que sa fonction principale est la fonction pens\u00e9e, alors la personne sera de type pens\u00e9e introvertie. <br><br>Par le m\u00e9canisme de compensation, la personne ayant une fonction d&rsquo;observation en fonction principale h\u00e9ritera automatiquement de l&rsquo;autre fonction d&rsquo;observation en inf\u00e9rieure. La fonction inf\u00e9rieure sera toujours de l&rsquo;attitude oppos\u00e9e \u00e0 celle de la fonction principale.<br><br>Les deux fonction-attitude restantes se partagent les places de la fonction auxiliaire et de la fonction tertiaire. Leurs attitudes ne sont pas mentionn\u00e9es par Jung, mais elles sont toutes les deux de m\u00eame nature, et toutes deux oppos\u00e9es en nature \u00e0 la fonction principale et \u00e0 la fonction inf\u00e9rieure &#8211; c&rsquo;est \u00e0 dire que si les fonctions principale et inf\u00e9rieure sont des fonctions d&rsquo;observation, alors les fonctions auxiliaire et tertiaire seront des fonctions de jugement. <\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-oppos\u00e9s-et-\u00e9quilibre-psychique\">Oppos\u00e9s et \u00e9quilibre psychique<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">Pour Jung et ses continuateurs le syst\u00e8me des fonctions est \u00e9quilibr\u00e9 dans tous ses aspects par des m\u00e9canismes de compensation et d&rsquo;oppos\u00e9s, et c\u2019est la tension entre ces oppos\u00e9s qui tire \u00e0 la fois vers l\u2019\u00e9quilibre et vers la croissance. C\u2019est par le processus de diff\u00e9renciation &#8211; l\u2019apport du contenu inconscient dans la conscience, que l\u2019individuation &#8211; devenir l\u2019individu que nous avons le potentiel d\u2019\u00eatre,  se r\u00e9alise.<br><br>Ce principe de compensation par les oppos\u00e9s est un des piliers de la typologie jungienne. Certaines typologies se r\u00e9clamant de Jung mais ne respectant pas ce principe de compensation fleurissent depuis quelques ann\u00e9es sur Internet. Le typologue averti ne s&rsquo;y trompera pas : en typologie jungienne chaque \u00e9l\u00e9ment doit toujours \u00eatre compens\u00e9 par son contraire dans la psych\u00e9. Pour Jung c&rsquo;est toujours le d\u00e9s\u00e9quilibre extr\u00eame et\/ou prolong\u00e9 des fonctions qui est l&rsquo;origine de la plupart des dysfonctionnements de la personnalit\u00e9 et des n\u00e9vroses.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-inconscient-selon-Jung\">L&rsquo;inconscient selon Jung<\/h5>\n\n\n\n<p class=\"has-normal-font-size\">La typologie jungienne a \u00e9t\u00e9 th\u00e9oris\u00e9e pour appr\u00e9hender le fonctionnement de la conscience. Cependant, il est int\u00e9ressant de se pencher sur les th\u00e9ories de Jung concernant l&rsquo;inconscient car cela permet de mieux comprendre le fonctionnement global de la psych\u00e9 chez ce th\u00e9oricien.<br><br>Pour Jung, tout commence avec <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Inconscient_collectif\">l&rsquo;inconscient collectif<\/a>, sorte de chaos originel, de point d&rsquo;entropie maximale de l&rsquo;univers, o\u00f9 rien n&rsquo;est diff\u00e9renci\u00e9 &#8211; et donc o\u00f9 tout ne fait qu&rsquo;un, porteur d&rsquo;un potentiel de cr\u00e9ation et de croissance immense. Dans les mythes de la cosmogonie, on retrouve souvent cet \u00e9tat divin o\u00f9 les oppos\u00e9s cohabitent, o\u00f9 \u00ab\u00a0le loup et l&rsquo;agneau dorment ensemble\u00a0\u00bb comme dans la proph\u00e9tie d&rsquo;\u00c9sa\u00efe. Pour Jung ces mythes sont la preuve de l&rsquo;existence de l&rsquo;inconscient collectif, des manifestations d&rsquo;un arch\u00e9type d&rsquo;un \u00e9tat primordial cherchant \u00e0 rappeler \u00e0 notre conscience d&rsquo;o\u00f9 elle vient.<br><br>De cet inconscient collectif va peu \u00e0 peu \u00e9merger un inconscient qui va commencer \u00e0 ordonner certains \u00e9l\u00e9ment du chaos. Cette minuscule partie de l&rsquo;inconscient collectif, engag\u00e9 dans un processus n\u00e9guentropique, va peu \u00e0 peu se condenser en un inconscient personnel. Plus les contenus vont s&rsquo;ordonner, plus la distinction entre les oppos\u00e9s va devenir claire, et plus la personnalit\u00e9 consciente va pouvoir \u00e9merger. Et de l&rsquo;inconscient personnel va \u00e9merger la conscience individuelle.<br><br>Nous voil\u00e0 en pr\u00e9sence d&rsquo;un nouveau n\u00e9 dont la conscience nouvelle, \u00e0 peine sortie de l&rsquo;inconscient collectif et de l&rsquo;inconscient personnel, va chercher \u00e0 s&rsquo;affirmer en tant qu&rsquo;entit\u00e9 autonome. Les premi\u00e8res ann\u00e9es de sa vie, ce nouvel \u00eatre va renforcer son ego, le si\u00e8ge de son identit\u00e9. Sa premi\u00e8re fonction cognitive va appara\u00eetre, et en s&rsquo;identifiant au fonctionnement de cette fonction il va rejeter le fonctionnement de la fonction oppos\u00e9 hors de sa conscience. Cette premi\u00e8re fonction rejet\u00e9e dans son inconscient personnel sera sa fonction inf\u00e9rieure. <br><br>Pour cr\u00e9er son identit\u00e9, la personne va devoir se constituer une personnalit\u00e9 consciente : le Moi (cf. Carl Jung, in&nbsp;<em>A\u00efon<\/em>, Le Moi). Se faisant elle va, par effet de compensation, donner naissance \u00e0 une entit\u00e9 autonome contraire qui r\u00e9sidera dans son inconscient personnel &#8211; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ombre_(psychologie_analytique)\">l&rsquo;ombre<\/a>. Elle s&rsquo;identifiera aussi \u00e0 un genre, et un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Animus\">animus<\/a> ou un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Anima\">anima<\/a> na\u00eetra dans son inconscient pour compenser ce dernier. Enfin, elle se constituera un masque social, un m\u00e9diateur qui permettra au Moi de communiquer avec le monde ext\u00e9rieure, la <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Persona_(psychologie_analytique)\">persona<\/a><\/em>. Ombre, animus, anima et <em>persona<\/em> sont ce que Jung appelait des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Arch%C3%A9type_(psychologie_analytique)\">arch\u00e9types<\/a>, des sch\u00e9ma primordiaux charg\u00e9s d&rsquo;une \u00e9nergie <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Numineux\">numineuse<\/a> servant de m\u00e9diateurs entre l&rsquo;inconscient collectif et la conscience.<br><br>La s\u00e9paration d&rsquo;avec l&rsquo;inconscient collectif est n\u00e9cessaire \u00e0 l&rsquo;individualisation, et la distinction des oppos\u00e9s est n\u00e9cessaire \u00e0 l&rsquo;identification. Cependant le processus de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Individuation_(psychologie_analytique)#:~:text=L%27individuation%20est%20un%20concept,psychiatre%20suisse%20Carl%20Gustav%20Jung.\">l&rsquo;individuation<\/a>, le but r\u00e9el de toute existence humaine, vient seulement de s&rsquo;enclencher. R\u00e9aliser l&rsquo;individuation, c&rsquo;est devenir l&rsquo;individu que nous avons le potentiel d&rsquo;\u00eatre en r\u00e9conciliant les oppos\u00e9s et en int\u00e9grant tous les contenus inconscients \u00e0 la conscience pour acc\u00e9der \u00e0 l&rsquo;arch\u00e9type du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Soi_(psychologie)\">Soi<\/a> &#8211; l&rsquo;enti\u00e8ret\u00e9 de la psych\u00e9 r\u00e9alis\u00e9e. (On retrouve l&rsquo;arch\u00e9type de cette qu\u00eate de l&rsquo;individuation dans le mythe arthurien de la qu\u00eate du<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Graal#:~:text=%C3%80%20partir%20du%20XIII%20e,le%20nom%20de%20Saint%20Graal.\"> Graal<\/a>, et plus largement dans toutes les contes et les r\u00e9cits de qu\u00eates h\u00e9ro\u00efques.) <br><br>En termes plus pragmatiques et plus concrets, l&rsquo;individuation se r\u00e9alise en partie par la diff\u00e9renciation et l&rsquo;int\u00e9gration des fonctions inf\u00e9rieures et en partie par le travail sur les arch\u00e9types via l&rsquo;imagination active et l&rsquo;interpr\u00e9tation des r\u00eaves.<br>La conscience est toujours en lien avec l&rsquo;inconscient personnel et l&rsquo;inconscient collectif qui la nourrissent et l&rsquo;\u00e9quilibrent, mais qui peuvent \u00e9galement la d\u00e9stabiliser et l&rsquo;envahir. <br><br>Mais l&rsquo;inconscient pour Jung n&rsquo;est pas ce d\u00e9potoir de la conscience  que Freud a th\u00e9oris\u00e9 o\u00f9 sont refoul\u00e9s monstres, peurs et frustrations sexuelles. C&rsquo;est au contraire pour Jung une sorte de champ qui nous relie \u00e0 l&rsquo;humanit\u00e9 pass\u00e9, pr\u00e9sente et future ; un champ de connaissances, d&rsquo;id\u00e9es, d&rsquo;\u00e9motions et d&rsquo;\u00e9nergies qui nous enseigne, nous inspire et \u00e0 le pouvoir de nous gu\u00e9rir.<br><br>Bien loin d&rsquo;\u00eatre construit sur le seul probl\u00e8me de la sexualit\u00e9 refoul\u00e9e du complexe d&rsquo;\u0152dipe, l&rsquo;inconscient jungien est constitu\u00e9 de l&rsquo;ensemble des mythes de l&rsquo;humanit\u00e9, et c&rsquo;est par le langage arch\u00e9typal que nous entrons en contact avec cet inconscient et que cet inconscient communique avec nous. <\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"has-text-color has-background has-text-align-center has-very-dark-gray-color has-light-green-cyan-background-color has-normal-font-size wp-block-heading\" id=\"CGJ-pour-aller-plus-loin\">Pour aller plus loin<\/h5>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-41 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-medium is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/51PXq4huG1L._SX316_BO1204203200_-191x300.jpg\" alt=\"\" class=\"wp-image-948\" width=\"191\" height=\"300\" srcset=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/51PXq4huG1L._SX316_BO1204203200_-191x300.jpg 191w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/51PXq4huG1L._SX316_BO1204203200_.jpg 318w\" sizes=\"(max-width: 191px) 100vw, 191px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-normal-font-size\"><strong>SEDILLOT Carole, <em>ABC de la psychologie jungienne<\/em><\/strong>, \u00c9ditions Grancher, 2003<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.amazon.fr\/ABC-psychologie-jungienne-Carole-S%C3%A9dillot\/dp\/2733907956\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/images.png\" alt=\"\" class=\"wp-image-953\" width=\"120\" srcset=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/images.png 323w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/images-300x145.png 300w\" sizes=\"(max-width: 323px) 100vw, 323px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-44 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-medium is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/41auNAz1BL._SX331_BO1204203200_-200x300.jpg\" alt=\"\" class=\"wp-image-908\" width=\"200\" height=\"300\" srcset=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/41auNAz1BL._SX331_BO1204203200_-200x300.jpg 200w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/41auNAz1BL._SX331_BO1204203200_.jpg 333w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-normal-font-size\"> <strong>JUNG Carl, <em>Psychological Types<\/em><\/strong>, traduit de l\u2019allemand par BAYNES H. G. en 1923 et pr\u00e9fac\u00e9 par BEEBE John, Routhledge Classics edition, New York, 2017<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.amazon.fr\/Psychological-Types-Carl-Jung\/dp\/1138687421\/ref=sr_1_4?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=2226MC5UVFSJB&amp;dchild=1&amp;keywords=psychological+types+jung&amp;qid=1592495776&amp;s=books&amp;sprefix=psychological+ty%2Cstripbooks%2C192&amp;sr=1-4\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/images.png\" alt=\"\" class=\"wp-image-953\" width=\"120\" height=\"78\"\/><\/a><\/figure>\n\n\n\n<p><strong>Note<\/strong> : L&rsquo;\u00e9dition fran\u00e7aise semble comporter des contresens dans la traduction. Elle est actuellement \u00e0 l&rsquo;\u00e9tude par notre \u00e9quipe. En attendant nous recommandons de pr\u00e9f\u00e9rence l&rsquo;\u00e9dition anglaise traduite sous la direction de C. G. Jung.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-47 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image aligncenter size-medium\"><img decoding=\"async\" loading=\"lazy\" width=\"193\" height=\"300\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-193x300.jpg\" alt=\"\" class=\"wp-image-1185\" srcset=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-193x300.jpg 193w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-600x933.jpg 600w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-659x1024.jpg 659w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-768x1194.jpg 768w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL-988x1536.jpg 988w, https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/08\/71Am0vA4KVL.jpg 1200w\" sizes=\"(max-width: 193px) 100vw, 193px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-normal-font-size\"> <strong>JUNG Carl, <em>The portable Jung<\/em><\/strong>, traduit par HULL R.F.C et \u00e9dit\u00e9 par CAMPBELL Joseph, Penguin Books Edition, New York, 1971<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.amazon.fr\/Portable-Jung-C-G-dp-0140150706\/dp\/0140150706\/ref=dp_ob_title_bk\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/typologieanalytique.com\/wp-content\/uploads\/2020\/06\/images.png\" alt=\"\" class=\"wp-image-953\" width=\"120\" height=\"78\"\/><\/a><\/figure>\n\n\n\n<p><strong>Note<\/strong> : Ce recueil des \u0153uvres clefs de la pens\u00e9e de Jung contient le chapitre \u00ab\u00a0Description g\u00e9n\u00e9rale des types\u00a0\u00bb de <em>Types psychologiques<\/em>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><a href=\"#CGJ-sommaire\">Retour au sommaire<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La typologie jungienne La th\u00e9orie des types issue de Types psychologiques de C. G. Jung constitue ce qu&rsquo;on appelle la typologie jungienne. C&rsquo;est la base th\u00e9orique de tous les mod\u00e8les typologiques \u00e0 seize types. En typologie jungienne, chaque type est nomm\u00e9 par sa fonction dominante, sans acronyme (ex : Penseur introverti). Le c\u00e2blage cognitif n&rsquo;est &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/typologieanalytique.com\/index.php\/la-typologie-jungienne\/\"> <span class=\"screen-reader-text\">La typologie jungienne<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"acf":[],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":""},"post_excerpt_stackable":"<p>La typologie jungienne La th\u00e9orie des types issue de Types psychologiques de C. G. Jung constitue ce qu&rsquo;on appelle la typologie jungienne. C&rsquo;est la base th\u00e9orique de tous les mod\u00e8les typologiques \u00e0 seize types.En typologie jungienne, chaque type est nomm\u00e9 par sa fonction dominante, sans acronyme (ex : Penseur introverti). Le c\u00e2blage cognitif n&rsquo;est constitu\u00e9 que de quatre fonctions \u00e9gosyntoniques (comme en typologie myersienne) mais seules les attitudes de la fonction dominante et de la fonction inf\u00e9rieure sont distingu\u00e9es &#8211; l&rsquo;attitude des fonctions auxiliaire et tertiaire restant incertaine.La th\u00e9orie des types de Jung constitue la base de la typologie analytique,\u2026<\/p>\n","category_list":"","author_info":{"name":"agagnier","url":"https:\/\/typologieanalytique.com\/index.php\/author\/agagnier\/"},"comments_num":"0 commentaire","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"agagnier","author_link":"https:\/\/typologieanalytique.com\/index.php\/author\/agagnier\/"},"uagb_comment_info":0,"uagb_excerpt":"La typologie jungienne La th\u00e9orie des types issue de Types psychologiques de C. G. Jung constitue ce qu&rsquo;on appelle la typologie jungienne. C&rsquo;est la base th\u00e9orique de tous les mod\u00e8les typologiques \u00e0 seize types. En typologie jungienne, chaque type est nomm\u00e9 par sa fonction dominante, sans acronyme (ex : Penseur introverti). Le c\u00e2blage cognitif n&rsquo;est\u2026","_links":{"self":[{"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/pages\/862"}],"collection":[{"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":73,"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/pages\/862\/revisions"}],"predecessor-version":[{"id":6881,"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/pages\/862\/revisions\/6881"}],"wp:attachment":[{"href":"https:\/\/typologieanalytique.com\/index.php\/wp-json\/wp\/v2\/media?parent=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}